{"id":5774,"date":"2019-11-16T13:14:28","date_gmt":"2019-11-16T13:14:28","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?product=tables-basses"},"modified":"2022-09-24T17:35:52","modified_gmt":"2022-09-24T17:35:52","slug":"table-basse-par-guerin-belgique-1958","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/galeria\/tables\/tables-basses\/table-basse-par-guerin-belgique-1958\/","title":{"rendered":"Table basse par Gu\u00e9rin &#8211; Belgique 1958"},"content":{"rendered":"<p>Table basse par Gu\u00e9rin &#8211; Belgique 1958<\/p>\n<hr \/>\n<p><b>Dimensions<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> 101 x 41 x 51<\/li>\n<li><b>inches:<\/b> 39.76 x 16.14 x 20.08<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Table basse en fer forg\u00e9, plateau en carreaux de c\u00e9ramiques peints \u00e0 la main.<\/p>\n<p>Sign\u00e9 et dat\u00e9 du fameux c\u00e9ramiste Gu\u00e9rin &#8211; Belgique 1958.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Dimensions<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> 101 x 41 x 51<\/li>\n<li><b>inches:<\/b> 39.76 x 16.14 x 20.08<\/li>\n<\/ul>\n","protected":false},"featured_media":5763,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[256,291],"product_tag":[],"class_list":["post-5774","product","type-product","status-publish","has-post-thumbnail","product_cat-tables","product_cat-tables-basses","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product\/5774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/media\/5763"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/media?parent=5774"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_brand?post=5774"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_cat?post=5774"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_tag?post=5774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}