{"id":2122,"date":"2011-01-01T00:00:00","date_gmt":"2011-01-01T00:00:00","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?product=lampes-de-table"},"modified":"2022-10-15T09:44:25","modified_gmt":"2022-10-15T09:44:25","slug":"lampe-de-table-en-ceramique","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/galeria\/luminaires\/lampes-de-table\/lampe-de-table-en-ceramique\/","title":{"rendered":"Lampe de table en c\u00e9ramique"},"content":{"rendered":"<p>Lampe de table en c\u00e9ramique<\/p>\n<hr \/>\n<p><b>Dimensions<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Diam 22 .H 26 , H+abat-jour 53<\/li>\n<li><b>inches:<\/b> Diam 8.66 .H 10.24 . H+abat-jour 20.87<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Lampe de table, c\u00e9ramique et motif sir\u00e8ne bronze appliqu\u00e9.<\/p>\n<p>Sign\u00e9 Pol Chambost.<\/p>\n<p>France.<\/p>\n<p><b>Dimensions<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Diam 22 .H 26 , H+abat-jour 53<\/li>\n<li><b>inches:<\/b> Diam 8.66 .H 10.24 . H+abat-jour 20.87<\/li>\n<\/ul>\n","protected":false},"featured_media":2114,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[333,264],"product_tag":[],"class_list":["post-2122","product","type-product","status-publish","has-post-thumbnail","product_cat-lampes-de-table","product_cat-luminaires","first","outofstock","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product\/2122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/media\/2114"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_brand?post=2122"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_cat?post=2122"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_tag?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}