{"id":19618,"date":"2023-02-18T10:36:35","date_gmt":"2023-02-18T10:36:35","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/product\/large-console-mirror-by-pier-luigi-colli-1940\/"},"modified":"2023-07-18T16:26:30","modified_gmt":"2023-07-18T16:26:30","slug":"console-miroir-2","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/galeria\/miroirs\/console-miroir\/console-miroir-2\/","title":{"rendered":"Grande console miroir par Pier Luigi Colli \u2013 Italie 1940"},"content":{"rendered":"<p><strong>Pier Luigi Colli<\/strong>\u00a0(Turin, Italie, 1895-1968)<\/p>\n<p>Artiste et designer italien. Il \u00e9tudie \u00e0 l\u2019\u00c9cole des Arts D\u00e9coratifs de Paris et revient en Italie dans les ann\u00e9es 1920 pour diriger l\u2019entreprise de meubles de sa famille \u00e0 Turin, fond\u00e9e en 1850 et c\u00e9l\u00e8bre pour ses beaux tapis, tissus et luminaires. Ses conceptions ont jou\u00e9 un r\u00f4le important dans le d\u00e9veloppement du mouvement Art Nouveau du d\u00e9but du XXe si\u00e8cle. La plupart des pi\u00e8ces de Pier Luigi repr\u00e9sentent le style Art d\u00e9co parisien. Il a souvent utilis\u00e9 des mat\u00e9riaux combin\u00e9s comme le fer, le laiton, le verre et le bois. La soci\u00e9t\u00e9 Colli a \u00e9galement travaill\u00e9 avec des architectes et des designers comme Gio Ponti et Carlo Mollino. Ils ont travaill\u00e9 sur des projets d\u2019ameublement comme le grand hall de l\u2019Universit\u00e9 de Turin et la succursale de Turin de la Banque d\u2019Italie. \u00c0 la mort de Pier Luigi en 1968, sa fille Claudia lui succ\u00e8de jusqu\u2019\u00e0 la fermeture de l\u2019entreprise dans les ann\u00e9es 1980, rendant les meubles tr\u00e8s recherch\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Grande console miroir en fer forg\u00e9 dor\u00e9, glace partiellement grav\u00e9e \u00e0 la meule et dor\u00e9e.<\/p>\n<p>Design: Pier Luigi Colli.<\/p>\n<p>Italie vers 1940.<\/p>\n<p>&nbsp;<\/p>\n<p><b>Dimensions<\/b><\/p>\n<p><b>cm:<\/b> 240 x 30 x 126<\/p>\n<p><b>inches:<\/b> 94.48 x 11.81 x 49.6<\/p>\n","protected":false},"featured_media":19590,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[456,342],"product_tag":[],"class_list":["post-19618","product","type-product","status-publish","has-post-thumbnail","product_cat-console-miroir","product_cat-miroirs","first","outofstock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product\/19618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/media\/19590"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/media?parent=19618"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_brand?post=19618"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_cat?post=19618"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/fr\/wp-json\/wp\/v2\/product_tag?post=19618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}