{"id":280,"count":14,"description":"","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/categoria-producto\/asientos1643813446\/sillas2\/","name":"Sillas","slug":"sillas2","taxonomy":"product_cat","parent":252,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat\/280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat\/252"}],"wp:post_type":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product?product_cat=280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}