{"id":6930,"date":"2021-02-07T17:59:02","date_gmt":"2021-02-07T17:59:02","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?product=esculturas"},"modified":"2022-09-19T11:59:14","modified_gmt":"2022-09-19T11:59:14","slug":"pareja-de-cabezas-de-personajes-francia","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/objetos-y-adornos\/objetos-decorativos\/pareja-de-cabezas-de-personajes-francia\/","title":{"rendered":"Pareja de cabezas de personajes &#8211; Francia"},"content":{"rendered":"<p>Pareja de cabezas de personajes &#8211; Francia<\/p>\n<hr \/>\n<p><b>Dimensiones<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Grande 13 x 10 x 19 Peque\u00f1a 11 x 10 x 11<\/li>\n<li><b>inches:<\/b> Grande 5.12 x 3.94 x 7.48 Peque\u00f1a 4.33 x 3.94 x 4.33<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Pareja de peque\u00f1as cabezas de personajes, bronce patinado oscuro.<\/p>\n<p>Firmado: Coutant 2005 &#8211; Tirada 2\/8<\/p>\n<p>Francia 2005<\/p>\n<p><b>Dimensiones<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Grande 13 x 10 x 19 Peque\u00f1a 11 x 10 x 11<\/li>\n<li><b>inches:<\/b> Grande 5.12 x 3.94 x 7.48 Peque\u00f1a 4.33 x 3.94 x 4.33<\/li>\n<\/ul>\n","protected":false},"featured_media":9157,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[465,268],"product_tag":[],"class_list":["post-6930","product","type-product","status-publish","has-post-thumbnail","product_cat-objetos-decorativos","product_cat-objetos-y-adornos","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/6930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/9157"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=6930"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=6930"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=6930"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=6930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}