{"id":42414,"date":"2026-07-05T13:46:58","date_gmt":"2026-07-05T13:59:56","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?post_type=product&#038;p=42414"},"modified":"2026-07-05T13:59:56","modified_gmt":"2026-07-05T13:59:56","slug":"mecedoras-de-jordi-vilanova-barcelona-1966","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/asientos1643813446\/sillones2\/mecedoras-de-jordi-vilanova-barcelona-1966\/","title":{"rendered":"Mecedoras de Jordi Vilanova &#8211; Barcelona 1966"},"content":{"rendered":"<p><strong>Jordi Vilanova i Bosch<\/strong>\u00a0(Barcelona, \u200b\u200bEspa\u00f1a, 1925-1998)<\/p>\n<p>Interiorista y ebanista catal\u00e1n. Estudi\u00f3 en la Escola del Treball i Oficis Art\u00edstics y en La Llotja, y se form\u00f3 en la Casa Busquets y en el taller de decoraci\u00f3n de Lluis Gili, hasta fundar su propia empresa de interiorismo en 1952. Fue miembro del grupo art\u00edstico multidisciplinario La Cantonada (1960-1975). Su mobiliario moderno y su planteamiento de los espacios no fueron entendidos por la gran mayor\u00eda, a la que iba dirigida su obra, y fue cierta burgues\u00eda catalana, deseosa de romper con los c\u00e1nones estil\u00edsticos anticuados, quien lo acogi\u00f3. Gran admirador y experto en dise\u00f1o n\u00f3rdico, Vilanova es conocido como el introductor en Espa\u00f1a de los muebles de madera blanca, es decir, muebles sin color ni barniz brillante, funcionales, sencillos y refinados. Su especialidad fue el mobiliario infantil, como el taburete Delta, que gan\u00f3 el Premio Delta de Plata que otorg\u00f3 ADI\/FAD en 1964. Otros dise\u00f1os representativos son: las sillas Tiracord y Billar (1961); la litera Montseny MP (1961); las mecedoras Tartera (1966) y Petit (1978) y el revistero Z (1987), dise\u00f1ado junto a su hijo Pau Vilanova. Todos estos muebles est\u00e1n expuestos en el Museo del Dise\u00f1o de Barcelona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raro par de mecedoras de haya te\u00f1ida y encerada, con acolchado y tela renovados con tejido de bucles de color gris-beige.<\/p>\n<p>Modelo \u00abTartera\u00bb, de Jordi Vilanova i Bosc.<\/p>\n<p>Espa\u00f1a, Barcelona, 1966.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong> 67 x 100 x 82 \u2013 asiento 38<\/p>\n<p><strong>inches<\/strong> 26.38 x 39.37 x 32.28 \u2013 asiento 14.96<\/p>\n","protected":false},"featured_media":42379,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[253,252],"product_tag":[],"class_list":["post-42414","product","type-product","status-publish","has-post-thumbnail","product_cat-sillones2","product_cat-asientos1643813446","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/42414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/42379"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=42414"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=42414"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=42414"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=42414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}