{"id":38839,"date":"2025-11-23T12:49:44","date_gmt":"2025-11-23T13:14:50","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?post_type=product&#038;p=38839"},"modified":"2025-11-23T13:14:50","modified_gmt":"2025-11-23T13:14:50","slug":"mueble-bar-esquinero-art-deco-barcelona-1930","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/auxiliares1643813499\/muebles-bar\/mueble-bar-esquinero-art-deco-barcelona-1930\/","title":{"rendered":"Mueble bar esquinero Art Dec\u00f3 &#8211; Barcelona 1930"},"content":{"rendered":"<p>Mueble bar esquinero Art Dec\u00f3 &#8211; Barcelona 1930<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a0114 x 60,5 x 129<\/p>\n<p><strong>inches<\/strong>\u00a044.88 x 23.82 x 50.79<\/p>\n<p><strong>Tri\u00e1ngulo<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a0114 x 81 x 81<\/p>\n<p><strong>inches<\/strong>\u00a044.88 x 31.89 x 31.89<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mueble bar esquinero Art Dec\u00f3 de madera maciza chapada en nogal y zebrano para las puertas, que se abren (dos laterales y una abatible) sobre un interior revestido de espejos, opalina negra y una l\u00e1mpara de techo, tres nichos abiertos y dos puertas en la parte inferior que dan acceso a un gran espacio de almacenamiento. Acabado encerado. Bisagras y tiradores de lat\u00f3n, cobre y n\u00edquel.<\/p>\n<p>Espa\u00f1a, Barcelona, hacia 1930.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a0114 x 60,5 x 129<\/p>\n<p><strong>inches<\/strong>\u00a044.88 x 23.82 x 50.79<\/p>\n<p><strong>Tri\u00e1ngulo<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a0114 x 81 x 81<\/p>\n<p><strong>inches<\/strong>\u00a044.88 x 31.89 x 31.89<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":38807,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[277,319],"product_tag":[],"class_list":["post-38839","product","type-product","status-publish","has-post-thumbnail","product_cat-auxiliares1643813499","product_cat-muebles-bar","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/38839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/38807"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=38839"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=38839"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=38839"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=38839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}