{"id":3597,"date":"2016-06-20T18:56:10","date_gmt":"2016-06-20T18:56:10","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?product=mesa-central"},"modified":"2022-10-29T09:36:50","modified_gmt":"2022-10-29T09:36:50","slug":"mesa-central-atribuida-a-adolf-loos","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/mesas\/auxiliares\/mesa-central-atribuida-a-adolf-loos\/","title":{"rendered":"Mesa central atribuida a Adolf Loos"},"content":{"rendered":"<p>Mesa de centro atribuida a Adolf Loos<\/p>\n<hr \/>\n<p><b>Dimensiones<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Diam. 74 x 69<\/li>\n<li><b>inches:<\/b> Diam. 29.13 x 27.17<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Espectacular mesa de centro de 10 columnas y 2 sobres, haya y pino macizos, chapado de caoba tintada y barnizada a mu\u00f1eca, montaje con sistema de tornillos en madera, alta calidad.<\/p>\n<p>Dise\u00f1o: atribuida a Adolf Loos<\/p>\n<p>Austria, Viena c. 1900<\/p>\n<p><b>Dimensiones<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Diam. 74 x 69<\/li>\n<li><b>inches:<\/b> Diam. 29.13 x 27.17<\/li>\n<\/ul>\n","protected":false},"featured_media":9683,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[258,259],"product_tag":[],"class_list":["post-3597","product","type-product","status-publish","has-post-thumbnail","product_cat-mesas","product_cat-auxiliares","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/3597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/9683"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=3597"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=3597"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=3597"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=3597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}