{"id":32685,"date":"2024-11-17T11:35:31","date_gmt":"2024-11-17T12:39:21","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?post_type=product&#038;p=32685"},"modified":"2024-11-17T12:39:21","modified_gmt":"2024-11-17T12:39:21","slug":"gran-mesa-de-comedor-italia-1940","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/mesas\/comedor\/gran-mesa-de-comedor-italia-1940\/","title":{"rendered":"Gran mesa de comedor &#8211; Italia 1940"},"content":{"rendered":"<p>Gran mesa de comedor &#8211; Italia 1940<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a0199 x 94 x 80<\/p>\n<p><strong>inches<\/strong>\u00a078.35 x 37.00 x 31.50<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gran mesa de comedor chapada en \u00e9bano de Macasar con el borde del sobre y filete de arce en la base. Barnizada a mu\u00f1eca.<\/p>\n<p>Italia circa 1940<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a0199 x 94 x 80<\/p>\n<p><strong>inches<\/strong>\u00a078.35 x 37.00 x 31.50<\/p>\n","protected":false},"featured_media":32668,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[258,289],"product_tag":[],"class_list":["post-32685","product","type-product","status-publish","has-post-thumbnail","product_cat-mesas","product_cat-comedor","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/32685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/32668"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=32685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=32685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=32685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=32685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}