{"id":32490,"date":"2024-10-29T16:55:49","date_gmt":"2024-10-29T17:16:11","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?post_type=product&#038;p=32490"},"modified":"2024-10-29T17:16:11","modified_gmt":"2024-10-29T17:16:11","slug":"juego-de-tres-mesas-nido-art-deco-francia-1930","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/mesas\/auxiliares\/juego-de-tres-mesas-nido-art-deco-francia-1930\/","title":{"rendered":"Juego de tres mesas nido Art Dec\u00f3 &#8211; Francia 1930"},"content":{"rendered":"<p>Juego de tres mesas nido Art Dec\u00f3 &#8211; Francia 1930<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong> \u2013 Mesa grande: 53 x 38 x 61,5<\/p>\n<p>Mesa mediana: 48 x 36 x 57,5<\/p>\n<p>Mesa peque\u00f1a: 43 x 34 x 53,5<\/p>\n<p><strong>inches<\/strong> \u2013 Mesa grande: 20.87 x 14.96 x 24.21<\/p>\n<p>Mesa mediana: 18.90 x 14.17 x 22.64<\/p>\n<p>Mesa peque\u00f1a: 16.93 x 13.39 x 21.06<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Juego de tres mesas nido Art Dec\u00f3 en nogal macizo y chapado de nogal. Barnizadas a mu\u00f1eca.<br \/>\nFrancia, hacia 1930.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong> \u2013 Mesa grande: 53 x 38 x 61,5<\/p>\n<p>Mesa mediana: 48 x 36 x 57,5<\/p>\n<p>Mesa peque\u00f1a: 43 x 34 x 53,5<\/p>\n<p><strong>inches<\/strong> \u2013 Mesa grande: 20.87 x 14.96 x 24.21<\/p>\n<p>Mesa mediana: 18.90 x 14.17 x 22.64<\/p>\n<p>Mesa peque\u00f1a: 16.93 x 13.39 x 21.06<\/p>\n","protected":false},"featured_media":32488,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[258,259],"product_tag":[],"class_list":["post-32490","product","type-product","status-publish","has-post-thumbnail","product_cat-mesas","product_cat-auxiliares","first","outofstock","shipping-taxable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/32490","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/32488"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=32490"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=32490"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=32490"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=32490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}