{"id":3162,"date":"2015-01-03T11:53:38","date_gmt":"2015-01-03T11:53:38","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?product=espejos"},"modified":"2023-03-04T12:46:46","modified_gmt":"2023-03-04T12:46:46","slug":"espejo-redondo-narciso-de-los-anos-60","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/espejos1643813618\/espejos-de-pared\/espejo-redondo-narciso-de-los-anos-60\/","title":{"rendered":"Espejo redondo Narciso de los a\u00f1os 60"},"content":{"rendered":"<p><strong>Sergio Mazza<\/strong> (Mil\u00e1n, Italia, 1931)<\/p>\n<p>Dise\u00f1ador y editor milan\u00e9s, Mazza estudia arquitectura en Lausana. Tras graduarse en 1954, abre su propio estudio. En 1960 cofunda Artemide con el ingeniero y dise\u00f1ador Ernesto Gismondi. Su objetivo es producir productos atemporales y t\u00e9cnicamente innovadores. Mazza dise\u00f1a el primer producto con \u00e9xito de la compa\u00f1\u00eda, la l\u00e1mpara Alfa (1959), que incorpora elementos naturales y artificiales de vidrio, m\u00e1rmol y metal.<\/p>\n<p>Otros dise\u00f1os notables incluyen la l\u00e1mpara Delta (1963), el sill\u00f3n Mida (1966), la barra Bacco (1967) y la silla Toga apilable (1968), hecha de una sola pieza de fibra de vidrio y que se muestra por primera vez en la Exposici\u00f3n Internacional del Mueble en Mil\u00e1n en 1969.<\/p>\n<p>En 1961, Mazza se separa de Gismondi y, junto con la arquitecta Giuliana Gramigna, abre su Studio Smc, con sede en Mil\u00e1n. Juntos dise\u00f1an muebles y otros productos para Arflex, Artemide, Cinova, Formica, Krupp, Poltrona Frau, Quattrifolio, Saporiti y Valenti. Desde 1966 hasta 1988, Mazza es codirector de Ottagono, una revista que desempe\u00f1a un papel importante en el apoyo a la cultura del dise\u00f1o italiano contempor\u00e1neo. En 1967, Mazza empieza a dise\u00f1ar para la empresa industrial italiana Olivari.<\/p>\n<p>A lo largo de su ilustre carrera, Mazza recibe muchos honores y premios, incluida una medalla de plata por su <em>Appartamento Italiano<\/em> en la exposici\u00f3n 10a Triennale de Mil\u00e1n en 1954, y un <em>Compasso d&#8217;Oro<\/em> por la l\u00e1mpara Delta en 1960. Un modelo de su silla Toga se conserva en el Museo V&amp;A de Londres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Espejo redondo Narciso en aluminio cepillado. Oxidaci\u00f3n original.<\/p>\n<p>Dise\u00f1o: Sergio Mazza para Artemide<\/p>\n<p>Italia c. 1960<\/p>\n<p>&nbsp;<\/p>\n<p>Tres unidades en stock.<\/p>\n<p><b>Dimensions<\/b><\/p>\n<ul>\n<li><b>cm:<\/b> Diam 62 x 4<\/li>\n<li><b>inches:<\/b> Diam 24.41 x 1.57<\/li>\n<\/ul>\n","protected":false},"featured_media":9269,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[455,343],"product_tag":[],"class_list":["post-3162","product","type-product","status-publish","has-post-thumbnail","product_cat-espejos-de-pared","product_cat-espejos1643813618","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/3162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/9269"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=3162"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=3162"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=3162"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=3162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}