{"id":27117,"date":"2023-12-23T09:42:49","date_gmt":"2023-12-23T09:56:50","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/?post_type=product&#038;p=27117"},"modified":"2023-12-23T09:56:56","modified_gmt":"2023-12-23T09:56:56","slug":"mueble-bar-o-gabinete-art-deco-francia-1930","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/almacenaje\/gabinetes\/mueble-bar-o-gabinete-art-deco-francia-1930\/","title":{"rendered":"Mueble bar o gabinete Art Dec\u00f3 &#8211; Francia 1930"},"content":{"rendered":"<p>Mueble bar o gabinete Art Dec\u00f3 &#8211; Francia 1930<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a065,5 x 48 x 128<\/p>\n<p><strong>inches<\/strong>\u00a025.79 x 18.90 x 50.39<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mueble bar o gabinete Art Dec\u00f3 de caoba maciza con chapado de palisandro de India en los laterales y en la parte superior y chapado de palisandro de R\u00edo en la puerta. Base y montantes lacados en negro. Tirador y bisagras de lat\u00f3n dorado. Barnizado a mu\u00f1eca.<\/p>\n<p>Atribuido a Christian Krass<\/p>\n<p>Francia, Lyon circa 1930<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a065,5 x 48 x 128<\/p>\n<p><strong>inches<\/strong>\u00a025.79 x 18.90 x 50.39<\/p>\n","protected":false},"featured_media":27097,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[412,694,277,319],"product_tag":[],"class_list":["post-27117","product","type-product","status-publish","has-post-thumbnail","product_cat-almacenaje","product_cat-gabinetes","product_cat-auxiliares1643813499","product_cat-muebles-bar","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/27117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/27097"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=27117"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=27117"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=27117"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=27117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}