{"id":12805,"date":"2022-08-01T09:46:51","date_gmt":"2022-08-01T09:46:51","guid":{"rendered":"https:\/\/finsdesiecles-artdeco.projectes.biz\/product\/console-vanity\/"},"modified":"2022-08-01T09:58:10","modified_gmt":"2022-08-01T09:58:10","slug":"consola-tocador","status":"publish","type":"product","link":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/galeria\/espejos1643813618\/espejos-consolas\/consola-tocador\/","title":{"rendered":"Consola tocador &#8211; Italia 1950"},"content":{"rendered":"<p>Consola tocador &#8211; Italia, 1950<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dimensiones<\/strong><\/p>\n<p><strong>cm<\/strong>\u00a090 x 38 x 182<br \/>\n<strong>inches<\/strong>\u00a035.43 x 14.96 x 71.65<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consola tocador de recibidor, estructura en madera maciza lacada en negro, bloque caj\u00f3n en palisandro, barnizado a mu\u00f1eca, barras y detalles en lat\u00f3n pulido, panel posterior forrado en escay original, espejo original (oxidaci\u00f3n).<\/p>\n<p>Atribu\u00eddo a Ico Parisi.<\/p>\n<p>Fabricante: Waip (sello)<\/p>\n<p>Italia c. 1950<\/p>\n<p>&nbsp;<\/p>\n<p><strong>cm<\/strong>\u00a090 x 38 x 182<br \/>\n<strong>inches<\/strong>\u00a035.43 x 14.96 x 71.65<\/p>\n<p><strong>cm<\/strong>\u00a090 x 38 x 182<br \/>\n<strong>inches<\/strong>\u00a035.43 x 14.96 x 71.65<\/p>\n","protected":false},"featured_media":11313,"template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","inline_featured_image":false},"product_brand":[],"product_cat":[457,449,277,343],"product_tag":[501],"class_list":["post-12805","product","type-product","status-publish","has-post-thumbnail","product_cat-espejos-consolas","product_cat-tocadores-es","product_cat-auxiliares1643813499","product_cat-espejos1643813618","product_tag-console-vanity-es","first","instock","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product\/12805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media\/11313"}],"wp:attachment":[{"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/media?parent=12805"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_brand?post=12805"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_cat?post=12805"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/finsdesiecles-artdeco.projectes.biz\/es\/wp-json\/wp\/v2\/product_tag?post=12805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}